{"id":10521,"date":"2022-02-28T21:58:18","date_gmt":"2022-02-28T20:58:18","guid":{"rendered":"https:\/\/www.polideas.it\/?post_type=product&#038;p=10521"},"modified":"2025-05-05T18:59:13","modified_gmt":"2025-05-05T16:59:13","slug":"koch-kuchengriff-aluminium-effekt-kuchenschrankgriff","status":"publish","type":"product","link":"https:\/\/www.polideas.it\/de\/it\/maniglie-pomelli-cucina\/maniglia-cucina-cook-maniglia-mobile-cucina-effetto-alluminio\/","title":{"rendered":"Cook K\u00fcchengriff - K\u00fcchenm\u00f6belgriff - Aluminium Effekt"},"content":{"rendered":"<p>Unverzichtbar und doch raffiniert in der Linie, <strong>der Cook K\u00fcchengriff von Polideas<\/strong> ist der klassische Griff, der durch seine Schlichtheit besticht, eine Eigenschaft, die sich f\u00fcr verschiedene Stilinterpretationen anbietet.<\/p>\n<p>Eine perfekte Erg\u00e4nzung f\u00fcr moderne K\u00fcchen, die <strong>Griff Koch<\/strong>Genau wie seine etwas l\u00e4ngere und schlankere Big-Version findet er dank seines immergr\u00fcnen Stils auch in klassischen K\u00fcchen seinen Platz.<\/p>\n<p><strong>Erh\u00e4ltlich in poliertem Chrom, Aluminiumeffekt, wei\u00dfem Lack und schwarzem Lack, <\/strong>passt perfekt zu geradlinigen M\u00f6beln mit modernen, tadellosen Oberfl\u00e4chen, genau wie sie.<\/p>\n<p>165 mm lang und 26 mm hoch, <strong>der Cook-Griff <\/strong>ist im Handumdrehen montiert und ver\u00e4ndert sofort das Aussehen der K\u00fcchenm\u00f6bel, indem es die Oberfl\u00e4chen vereinheitlicht und ihnen eine angeborene Eleganz verleiht.<\/p>","protected":false},"excerpt":{"rendered":"<p>Essenziale eppure ricercata nella linea, la maniglia cucina Cook di Polideas \u00e8 la classica maniglia che piace per la sua semplicit\u00e0, qualit\u00e0 che si presta a diverse interpretazioni di stile. Complemento perfetto delle cucine moderne, la maniglia Cook, esattamente come la sua versione Big leggermente pi\u00f9 lunga e sottile, trova collocazione anche nelle cucine classiche [&#8230;]\n","protected":false},"featured_media":14556,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[37],"product_tag":[3149,3150,3151,3152,3153,3154,3155,3156,3176,3100,3159,3160,3161],"class_list":["post-10521","product","type-product","status-publish","has-post-thumbnail","product_cat-maniglie-pomelli-cucina","product_tag-maniglia","product_tag-maniglia-anta-cucina","product_tag-maniglia-anta-mobile","product_tag-maniglia-cassettiera","product_tag-maniglia-cassetto","product_tag-maniglia-cassetto-cucina","product_tag-maniglia-cucina","product_tag-maniglia-design","product_tag-maniglia-interasse-128mm","product_tag-maniglia-mobile","product_tag-maniglia-mobile-al-miglior-prezzo","product_tag-maniglia-mobile-arredamento","product_tag-maniglia-per-mobile-cucina","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.polideas.it\/de\/wp-json\/wp\/v2\/product\/10521","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.polideas.it\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.polideas.it\/de\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.polideas.it\/de\/wp-json\/wp\/v2\/comments?post=10521"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.polideas.it\/de\/wp-json\/wp\/v2\/media\/14556"}],"wp:attachment":[{"href":"https:\/\/www.polideas.it\/de\/wp-json\/wp\/v2\/media?parent=10521"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.polideas.it\/de\/wp-json\/wp\/v2\/product_brand?post=10521"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.polideas.it\/de\/wp-json\/wp\/v2\/product_cat?post=10521"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.polideas.it\/de\/wp-json\/wp\/v2\/product_tag?post=10521"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}